{"id":494,"date":"2014-07-01T17:33:07","date_gmt":"2014-07-01T15:33:07","guid":{"rendered":"http:\/\/www.memo-media.de\/blog\/?p=494"},"modified":"2021-03-29T12:22:45","modified_gmt":"2021-03-29T10:22:45","slug":"special-effects-pyrotechnik","status":"publish","type":"post","link":"https:\/\/www.memo-media.de\/blog\/special-effects-pyrotechnik\/","title":{"rendered":"Special Effects &#038; Pyrotechnik &#8211; pure, laute Emotion"},"content":{"rendered":"<p>Die Kraft der Special Effects und der Pyrotechnik &#8211; diese Erkenntnis traf mich wie ein Blitz! <a title=\"The Dome bei RTL2\" href=\"https:\/\/www.tvnow.de\/shows\/the-dome-1842\" target=\"_blank\" rel=\"noopener noreferrer\">The Dome<\/a>, vor vielen Jahren. Auftritt der <a title=\"No Angels bei Wikipedia\" href=\"https:\/\/de.wikipedia.org\/wiki\/No_Angels\" target=\"_blank\" rel=\"noopener noreferrer\">No Angels<\/a>. Taktgenau zur Choreographie z\u00fcndeten wir zehn\u00a0[memo_rubrik id=2625]Konfettibomben[\/memo_rubrik] genau am B\u00fchnenrand. Der Eindruck, die riesigen Konfettiwirbel seien allein durch die Tanzschritte der K\u00fcnstlerinnen ausgel\u00f6st worden, war perfekt: Die Zuschauer sind ausgeflippt. Sie schrien, johlten und \u00fcberschlugen sich vor Begeisterung. Sie waren dabei lauter als das Gesetz erlaubt. \u00dcber 130 Dezibel \u2013 das muss man sich mal vorstellen: Die Reaktion ist lauter als das Ereignis.<\/p>\n<h3>Das Echo der Begeisterung st\u00e4rker als der Ton!<\/h3>\n<p>Seitdem wei\u00df ich, dass man Begeisterung messen kann. Gute und pr\u00e4zise platzierte Special Effects puschen Emotionen, die in der Luft liegen, b\u00fcndeln sie und lassen sie explodieren.\u00a0[memo_rubrik id=243]Special Effects[\/memo_rubrik] und\u00a0[memo_rubrik id=1684]Pyrotechnik[\/memo_rubrik] &#8211; das ist der Stoff, aus dem die unvergesslichen Momente sind. Kein Mensch kann sich alle Programmpunkte eines ganzen Events merken, im R\u00fcckblick sind es immer einzeln herausragende Momente, die in der Erinnerung bleiben. Und diese oft akzentuiert durch Special Effects.<\/p>\n<h3>Special Effects\u00a0 &#8211; pure Emotion, visualisiert durch pyrotechnische Effekte<\/h3>\n<p>Der Eindruck, den die Produktion hinterl\u00e4sst, und das, was sich in Zeitungen, im Fernsehen und auf Facebook wiederfindet \u2013 pure Emotion, visualisiert durch [memo_rubrik id=243]pyrotechnische Effekte[\/memo_rubrik]: Eine hei\u00dfe Show braucht Special Effects, Feuer, eine romantische Szene zarten Nebel. Wenn die letzten T\u00f6ne einer Ballade, in der eine S\u00e4ngerin ihr Herzblut singt, in ein gro\u00dfes Meer von blinkenden Font\u00e4nen sinken, r\u00fchrt das Menschen zu Tr\u00e4nen. Wenn die K\u00fcnstler um ein lebendig knisterndes Lagerfeuer sitzen, wird die Atmosph\u00e4re echt, auch wenn die Schneelandschaft auf der B\u00fchne aus Plastik ist.<\/p>\n<h3>Effekte sprechen Sinne an!<\/h3>\n<p>Wenn ein Titel in eine Traumszene entf\u00fchren soll, verh\u00fcllt weicher, wei\u00dfer, sorgf\u00e4ltig bemessener\u00a0[memo_rubrik id=1095]Nebel[\/memo_rubrik] den Boden und die S\u00e4ngerin schwebt auf Wolken. Effekte sprechen die Sinne an und verst\u00e4rken Stimmungen ins F\u00fchlbare. Manchmal reicht schon eine Handvoll Flitter im richtigen Moment in die\u00a0[memo_rubrik id=992]Windmaschine[\/memo_rubrik] gehaucht aus, um m\u00e4rchenhafte Stimmung zu verbreiten. Produkte sind auf Wirkung angewiesen. Bestimmte Effekte sind an bestimmte Gef\u00fchlszust\u00e4nde gebunden. Sie verdeutlichen Emotionen, die man filmisch nicht darstellen kann. Ohne [memo_rubrik id=2405]brennende \u00d6lf\u00e4sser[\/memo_rubrik], an denen sich arme Menschen die H\u00e4nde w\u00e4rmen, kommt keine Ghetto-Stimmung auf. Die Feuerschale geh\u00f6rt zum Schlager wie der Reim von Herz auf Schmerz. Die Klassiker sind l\u00e4ngst zu inneren Bildern geworden. Doch \u00fcberraschende, verbl\u00fcffende, nicht die platten und immer gleichen Effekte erzeugen den nachhaltigen Eindruck und schaffen Showmagie.<\/p>\n<h3>Ganze Geschichten lassen sich mit Effekten erz\u00e4hlen<\/h3>\n<p>Die\u00a0[memo_rubrik id=89]Flammen[\/memo_rubrik] an der B\u00fchnenvorderkante brennen, die Zuschauer sp\u00fcren die W\u00e4rme auf dem Gesicht. Auf dem Video-Content rollen riesige Feuerwolken gleicher Farbigkeit. Die fein abgestimmte Kombination von Feuer, Flammen, Hitze und der Feuerwalze im Hintergrund macht den Eindruck so echt, dass das Publikum bei Udo Lindenbergs Tour \u00bbIch mach mein Ding\u00ab das Geschehen auf der\u00a0[memo_rubrik id=188]B\u00fchne[\/memo_rubrik] als infernalisches\u00a0[memo_rubrik id=861]Gro\u00dffeuer[\/memo_rubrik] empfunden hat. Die lautstarke Begeisterung des Publikums \u00fcberschritt wohl einmal mehr die gesetzliche Grenze.<\/p>\n<h3>Das Spiel mit Flammen, Licht, Nebel und Wind setzt sich in der Erinnerung fest<\/h3>\n<p>Warum bestellen\u00a0[memo_rubrik id=2024]Regisseure[\/memo_rubrik] oder Produktionsleiter oft lieber zehn Feuerschalen als einen Effektgestalter, der sie im Vorfeld ber\u00e4t und aus dem unendlichen Spektrum der M\u00f6glichkeiten eine ma\u00dfgeschneiderte Dosis Magie f\u00fcr einen unvergesslichen Augenblick (er-)findet? In der Erinnerung redet kein Zuschauer von der Dauer des Ereignisses, sondern von den gro\u00dfen opulenten Bildern, die er erlebt hat: Das wird jahrelang weitererz\u00e4hlt. Es ist das fl\u00fcchtige Spiel mit den Specials Effects, mit Flammen, Licht, Nebel und Wind, das sich in der Erinnerung festsetzt. Wer das schafft, hat sein Pulver nicht verschossen und auch sein Geld nicht verbrannt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Kraft der Special Effects und der Pyrotechnik &#8211; diese Erkenntnis traf mich wie ein Blitz! The Dome, vor vielen&#8230;<\/p>\n","protected":false},"author":11,"featured_media":513,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[5,7,454],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.5 (Yoast SEO v20.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Special Effects &amp; Pyrotechnik - pure, laute Emotion<\/title>\n<meta name=\"description\" content=\"Die Emotion von Special Effects und Pyrotechnik bei Events und Veranstaltungen ist beachtlich - mehr dazu im Blog f\u00fcr die Eventplanung von memo-media.de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.memo-media.de\/blog\/special-effects-pyrotechnik\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Special Effects &amp; Pyrotechnik - pure, laute Emotion\" \/>\n<meta property=\"og:description\" content=\"Die Emotion von Special Effects und Pyrotechnik bei Events und Veranstaltungen ist beachtlich - mehr dazu im Blog f\u00fcr die Eventplanung von memo-media.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.memo-media.de\/blog\/special-effects-pyrotechnik\/\" \/>\n<meta property=\"og:site_name\" content=\"memo-media Blog f\u00fcr die Eventplanung\" \/>\n<meta property=\"article:published_time\" content=\"2014-07-01T15:33:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-29T10:22:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.memo-media.de\/blog\/wp-content\/uploads\/2014\/07\/ap4_5613-fuer-blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Friederike Unverzagt\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Friederike Unverzagt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.memo-media.de\/blog\/special-effects-pyrotechnik\/\",\"url\":\"https:\/\/www.memo-media.de\/blog\/special-effects-pyrotechnik\/\",\"name\":\"Special Effects & Pyrotechnik - pure, laute Emotion\",\"isPartOf\":{\"@id\":\"https:\/\/www.memo-media.de\/blog\/#website\"},\"datePublished\":\"2014-07-01T15:33:07+00:00\",\"dateModified\":\"2021-03-29T10:22:45+00:00\",\"author\":{\"@id\":\"https:\/\/www.memo-media.de\/blog\/#\/schema\/person\/b60bf5cc14935084f69be218189ff67e\"},\"description\":\"Die Emotion von Special Effects und Pyrotechnik bei Events und Veranstaltungen ist beachtlich - mehr dazu im Blog f\u00fcr die Eventplanung von memo-media.de\",\"breadcrumb\":{\"@id\":\"https:\/\/www.memo-media.de\/blog\/special-effects-pyrotechnik\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.memo-media.de\/blog\/special-effects-pyrotechnik\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.memo-media.de\/blog\/special-effects-pyrotechnik\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.memo-media.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Special Effects &#038; Pyrotechnik &#8211; pure, laute Emotion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.memo-media.de\/blog\/#website\",\"url\":\"https:\/\/www.memo-media.de\/blog\/\",\"name\":\"memo-media Blog f\u00fcr die Eventplanung\",\"description\":\"News und Facts aus der Eventbranche f\u00fcr die Eventbranche\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.memo-media.de\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.memo-media.de\/blog\/#\/schema\/person\/b60bf5cc14935084f69be218189ff67e\",\"name\":\"Friederike Unverzagt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.memo-media.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.memo-media.de\/blog\/wp-content\/uploads\/2014\/07\/friederike3_bz9a1632_neu-150x128.jpg\",\"contentUrl\":\"https:\/\/www.memo-media.de\/blog\/wp-content\/uploads\/2014\/07\/friederike3_bz9a1632_neu-150x128.jpg\",\"caption\":\"Friederike Unverzagt\"},\"description\":\"Im Juni 2008 gr\u00fcnden Friederike Unverzagt, Konrad Kuschel und Marek Lehmann die Elements Entertainment GmbH. Heute besteht das Team aus zehn festangestellten Mitarbeitern an den Standorten Berlin und Bielefeld. \\\"Unsere Arbeit umfasst die Kreation, Planung und Produktion unverwechselbarer Showereignisse, die lange wirken. Wir erschaffen f\u00fcr Sie einzigartige Momente, die Menschen ins Staunen versetzen, \u00fcberraschen, ergreifen und in jedem Fall - begeistern.\\\"\",\"sameAs\":[\"http:\/\/www.elem-ent.com\/home\/\"],\"url\":\"https:\/\/www.memo-media.de\/blog\/author\/friederike-unzerzagt\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Special Effects & Pyrotechnik - pure, laute Emotion","description":"Die Emotion von Special Effects und Pyrotechnik bei Events und Veranstaltungen ist beachtlich - mehr dazu im Blog f\u00fcr die Eventplanung von memo-media.de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.memo-media.de\/blog\/special-effects-pyrotechnik\/","og_locale":"de_DE","og_type":"article","og_title":"Special Effects & Pyrotechnik - pure, laute Emotion","og_description":"Die Emotion von Special Effects und Pyrotechnik bei Events und Veranstaltungen ist beachtlich - mehr dazu im Blog f\u00fcr die Eventplanung von memo-media.de","og_url":"https:\/\/www.memo-media.de\/blog\/special-effects-pyrotechnik\/","og_site_name":"memo-media Blog f\u00fcr die Eventplanung","article_published_time":"2014-07-01T15:33:07+00:00","article_modified_time":"2021-03-29T10:22:45+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.memo-media.de\/blog\/wp-content\/uploads\/2014\/07\/ap4_5613-fuer-blog.jpg","type":"image\/jpeg"}],"author":"Friederike Unverzagt","twitter_misc":{"Verfasst von":"Friederike Unverzagt","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.memo-media.de\/blog\/special-effects-pyrotechnik\/","url":"https:\/\/www.memo-media.de\/blog\/special-effects-pyrotechnik\/","name":"Special Effects & Pyrotechnik - pure, laute Emotion","isPartOf":{"@id":"https:\/\/www.memo-media.de\/blog\/#website"},"datePublished":"2014-07-01T15:33:07+00:00","dateModified":"2021-03-29T10:22:45+00:00","author":{"@id":"https:\/\/www.memo-media.de\/blog\/#\/schema\/person\/b60bf5cc14935084f69be218189ff67e"},"description":"Die Emotion von Special Effects und Pyrotechnik bei Events und Veranstaltungen ist beachtlich - mehr dazu im Blog f\u00fcr die Eventplanung von memo-media.de","breadcrumb":{"@id":"https:\/\/www.memo-media.de\/blog\/special-effects-pyrotechnik\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.memo-media.de\/blog\/special-effects-pyrotechnik\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.memo-media.de\/blog\/special-effects-pyrotechnik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.memo-media.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Special Effects &#038; Pyrotechnik &#8211; pure, laute Emotion"}]},{"@type":"WebSite","@id":"https:\/\/www.memo-media.de\/blog\/#website","url":"https:\/\/www.memo-media.de\/blog\/","name":"memo-media Blog f\u00fcr die Eventplanung","description":"News und Facts aus der Eventbranche f\u00fcr die Eventbranche","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.memo-media.de\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.memo-media.de\/blog\/#\/schema\/person\/b60bf5cc14935084f69be218189ff67e","name":"Friederike Unverzagt","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.memo-media.de\/blog\/#\/schema\/person\/image\/","url":"https:\/\/www.memo-media.de\/blog\/wp-content\/uploads\/2014\/07\/friederike3_bz9a1632_neu-150x128.jpg","contentUrl":"https:\/\/www.memo-media.de\/blog\/wp-content\/uploads\/2014\/07\/friederike3_bz9a1632_neu-150x128.jpg","caption":"Friederike Unverzagt"},"description":"Im Juni 2008 gr\u00fcnden Friederike Unverzagt, Konrad Kuschel und Marek Lehmann die Elements Entertainment GmbH. Heute besteht das Team aus zehn festangestellten Mitarbeitern an den Standorten Berlin und Bielefeld. \"Unsere Arbeit umfasst die Kreation, Planung und Produktion unverwechselbarer Showereignisse, die lange wirken. Wir erschaffen f\u00fcr Sie einzigartige Momente, die Menschen ins Staunen versetzen, \u00fcberraschen, ergreifen und in jedem Fall - begeistern.\"","sameAs":["http:\/\/www.elem-ent.com\/home\/"],"url":"https:\/\/www.memo-media.de\/blog\/author\/friederike-unzerzagt\/"}]}},"_links":{"self":[{"href":"https:\/\/www.memo-media.de\/blog\/wp-json\/wp\/v2\/posts\/494"}],"collection":[{"href":"https:\/\/www.memo-media.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.memo-media.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.memo-media.de\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.memo-media.de\/blog\/wp-json\/wp\/v2\/comments?post=494"}],"version-history":[{"count":20,"href":"https:\/\/www.memo-media.de\/blog\/wp-json\/wp\/v2\/posts\/494\/revisions"}],"predecessor-version":[{"id":13268,"href":"https:\/\/www.memo-media.de\/blog\/wp-json\/wp\/v2\/posts\/494\/revisions\/13268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.memo-media.de\/blog\/wp-json\/wp\/v2\/media\/513"}],"wp:attachment":[{"href":"https:\/\/www.memo-media.de\/blog\/wp-json\/wp\/v2\/media?parent=494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.memo-media.de\/blog\/wp-json\/wp\/v2\/categories?post=494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.memo-media.de\/blog\/wp-json\/wp\/v2\/tags?post=494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}